  {"id":3642,"date":"2022-04-20T15:29:53","date_gmt":"2022-04-20T13:29:53","guid":{"rendered":"https:\/\/www.mastphotogrant.com\/?page_id=3642"},"modified":"2022-04-20T15:30:06","modified_gmt":"2022-04-20T13:30:06","slug":"i-membri-della-giuria-della-terza-edizione","status":"publish","type":"page","link":"https:\/\/www.mastphotogrant.com\/it\/edizioni-precedenti\/terza-edizione-2011-12\/i-membri-della-giuria-della-terza-edizione\/","title":{"rendered":"I membri della Giuria della III edizione del concorso fotografico sono:"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"parent":803,"menu_order":39,"comment_status":"closed","ping_status":"closed","template":"page-jury.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3642","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mastphotogrant.com\/it\/wp-json\/wp\/v2\/pages\/3642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mastphotogrant.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mastphotogrant.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mastphotogrant.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mastphotogrant.com\/it\/wp-json\/wp\/v2\/comments?post=3642"}],"version-history":[{"count":2,"href":"https:\/\/www.mastphotogrant.com\/it\/wp-json\/wp\/v2\/pages\/3642\/revisions"}],"predecessor-version":[{"id":3650,"href":"https:\/\/www.mastphotogrant.com\/it\/wp-json\/wp\/v2\/pages\/3642\/revisions\/3650"}],"up":[{"embeddable":true,"href":"https:\/\/www.mastphotogrant.com\/it\/wp-json\/wp\/v2\/pages\/803"}],"wp:attachment":[{"href":"https:\/\/www.mastphotogrant.com\/it\/wp-json\/wp\/v2\/media?parent=3642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}